{"id":938,"date":"2014-06-24T00:00:00","date_gmt":"2014-06-23T22:00:00","guid":{"rendered":"https:\/\/itwgse.com\/news\/request-a-quote\/"},"modified":"2020-07-14T15:55:36","modified_gmt":"2020-07-14T13:55:36","slug":"request-a-quote","status":"publish","type":"post","link":"https:\/\/itwgse.com\/es\/news\/request-a-quote\/","title":{"rendered":"Request a quote ?"},"content":{"rendered":"<h2>Request a quote<\/h2>\n<p>It has never been easier to request a quote. We have set-up an inquiry form to ease your part of the job.<br \/>\nJust fill in the enquiry formula and press submit quotation.<\/p>\n<p>We will get back to you with a quotation as soon as possible.<\/p>\n<p>It goes without saying that you of course still are most welcome to contact us via mail or\u00a0on the phone as well<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Request a quote It has never been easier to request a quote. We have set-up an inquiry form to ease your part of the&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-938","post","type-post","status-publish","format-standard","hentry","category-ikke-kategoriseret"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Request a quote - Inquiry form to ease your part | ITW GSE<\/title>\n<meta name=\"description\" content=\"It has never been easier to request a quote. We have set-up an inquiry form and you only have to fill in the enquiry formula and press submit quotation.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/itwgse.com\/news\/request-a-quote\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Request a quote - Inquiry form to ease your part | ITW GSE\" \/>\n<meta property=\"og:description\" content=\"It has never been easier to request a quote. We have set-up an inquiry form and you only have to fill in the enquiry formula and press submit quotation.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/itwgse.com\/news\/request-a-quote\/\" \/>\n<meta property=\"og:site_name\" content=\"ITW GSE\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ITWGSE\/\" \/>\n<meta property=\"article:published_time\" content=\"2014-06-23T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-14T13:55:36+00:00\" \/>\n<meta name=\"author\" content=\"itw_admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"itw_admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/itwgse.com\\\/news\\\/request-a-quote\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/itwgse.com\\\/news\\\/request-a-quote\\\/\"},\"author\":{\"name\":\"itw_admin\",\"@id\":\"https:\\\/\\\/itwgse.com\\\/#\\\/schema\\\/person\\\/fbdad06eb1c46b74a6051c6a3d734a65\"},\"headline\":\"Request a quote ?\",\"datePublished\":\"2014-06-23T22:00:00+00:00\",\"dateModified\":\"2020-07-14T13:55:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/itwgse.com\\\/news\\\/request-a-quote\\\/\"},\"wordCount\":75,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/itwgse.com\\\/#organization\"},\"articleSection\":[\"Ikke-kategoriseret\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/itwgse.com\\\/news\\\/request-a-quote\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/itwgse.com\\\/news\\\/request-a-quote\\\/\",\"url\":\"https:\\\/\\\/itwgse.com\\\/news\\\/request-a-quote\\\/\",\"name\":\"Request a quote - Inquiry form to ease your part | ITW GSE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/itwgse.com\\\/#website\"},\"datePublished\":\"2014-06-23T22:00:00+00:00\",\"dateModified\":\"2020-07-14T13:55:36+00:00\",\"description\":\"It has never been easier to request a quote. We have set-up an inquiry form and you only have to fill in the enquiry formula and press submit quotation.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/itwgse.com\\\/news\\\/request-a-quote\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/itwgse.com\\\/news\\\/request-a-quote\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/itwgse.com\\\/news\\\/request-a-quote\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/itwgse.com\\\/es\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Request a quote ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/itwgse.com\\\/#website\",\"url\":\"https:\\\/\\\/itwgse.com\\\/\",\"name\":\"ITW GSE\",\"description\":\"It&#039;s all about connections\",\"publisher\":{\"@id\":\"https:\\\/\\\/itwgse.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/itwgse.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/itwgse.com\\\/#organization\",\"name\":\"ITW GSE\",\"url\":\"https:\\\/\\\/itwgse.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/itwgse.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/itwgse.com\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/itwgse.com\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo.png\",\"width\":302,\"height\":237,\"caption\":\"ITW GSE\"},\"image\":{\"@id\":\"https:\\\/\\\/itwgse.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ITWGSE\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/itw-gse\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCTUIMvyaOPfYIqzP8enZ8yw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/itwgse.com\\\/#\\\/schema\\\/person\\\/fbdad06eb1c46b74a6051c6a3d734a65\",\"name\":\"itw_admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c48e5561ccbd04a85248a18f6e58b84e4a9b8b0dbf59fa0a37a46fe1f2de4614?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c48e5561ccbd04a85248a18f6e58b84e4a9b8b0dbf59fa0a37a46fe1f2de4614?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c48e5561ccbd04a85248a18f6e58b84e4a9b8b0dbf59fa0a37a46fe1f2de4614?s=96&d=mm&r=g\",\"caption\":\"itw_admin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Request a quote - Inquiry form to ease your part | ITW GSE","description":"It has never been easier to request a quote. We have set-up an inquiry form and you only have to fill in the enquiry formula and press submit quotation.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/itwgse.com\/news\/request-a-quote\/","og_locale":"es_ES","og_type":"article","og_title":"Request a quote - Inquiry form to ease your part | ITW GSE","og_description":"It has never been easier to request a quote. We have set-up an inquiry form and you only have to fill in the enquiry formula and press submit quotation.","og_url":"https:\/\/itwgse.com\/news\/request-a-quote\/","og_site_name":"ITW GSE","article_publisher":"https:\/\/www.facebook.com\/ITWGSE\/","article_published_time":"2014-06-23T22:00:00+00:00","article_modified_time":"2020-07-14T13:55:36+00:00","author":"itw_admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"itw_admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/itwgse.com\/news\/request-a-quote\/#article","isPartOf":{"@id":"https:\/\/itwgse.com\/news\/request-a-quote\/"},"author":{"name":"itw_admin","@id":"https:\/\/itwgse.com\/#\/schema\/person\/fbdad06eb1c46b74a6051c6a3d734a65"},"headline":"Request a quote ?","datePublished":"2014-06-23T22:00:00+00:00","dateModified":"2020-07-14T13:55:36+00:00","mainEntityOfPage":{"@id":"https:\/\/itwgse.com\/news\/request-a-quote\/"},"wordCount":75,"commentCount":0,"publisher":{"@id":"https:\/\/itwgse.com\/#organization"},"articleSection":["Ikke-kategoriseret"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/itwgse.com\/news\/request-a-quote\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/itwgse.com\/news\/request-a-quote\/","url":"https:\/\/itwgse.com\/news\/request-a-quote\/","name":"Request a quote - Inquiry form to ease your part | ITW GSE","isPartOf":{"@id":"https:\/\/itwgse.com\/#website"},"datePublished":"2014-06-23T22:00:00+00:00","dateModified":"2020-07-14T13:55:36+00:00","description":"It has never been easier to request a quote. We have set-up an inquiry form and you only have to fill in the enquiry formula and press submit quotation.","breadcrumb":{"@id":"https:\/\/itwgse.com\/news\/request-a-quote\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/itwgse.com\/news\/request-a-quote\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/itwgse.com\/news\/request-a-quote\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/itwgse.com\/es\/home\/"},{"@type":"ListItem","position":2,"name":"Request a quote ?"}]},{"@type":"WebSite","@id":"https:\/\/itwgse.com\/#website","url":"https:\/\/itwgse.com\/","name":"ITW GSE","description":"It&#039;s all about connections","publisher":{"@id":"https:\/\/itwgse.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/itwgse.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/itwgse.com\/#organization","name":"ITW GSE","url":"https:\/\/itwgse.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/itwgse.com\/#\/schema\/logo\/image\/","url":"https:\/\/itwgse.com\/wp-content\/uploads\/2018\/11\/logo.png","contentUrl":"https:\/\/itwgse.com\/wp-content\/uploads\/2018\/11\/logo.png","width":302,"height":237,"caption":"ITW GSE"},"image":{"@id":"https:\/\/itwgse.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ITWGSE\/","https:\/\/www.linkedin.com\/company\/itw-gse\/","https:\/\/www.youtube.com\/channel\/UCTUIMvyaOPfYIqzP8enZ8yw"]},{"@type":"Person","@id":"https:\/\/itwgse.com\/#\/schema\/person\/fbdad06eb1c46b74a6051c6a3d734a65","name":"itw_admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c48e5561ccbd04a85248a18f6e58b84e4a9b8b0dbf59fa0a37a46fe1f2de4614?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c48e5561ccbd04a85248a18f6e58b84e4a9b8b0dbf59fa0a37a46fe1f2de4614?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c48e5561ccbd04a85248a18f6e58b84e4a9b8b0dbf59fa0a37a46fe1f2de4614?s=96&d=mm&r=g","caption":"itw_admin"}}]}},"_links":{"self":[{"href":"https:\/\/itwgse.com\/es\/wp-json\/wp\/v2\/posts\/938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/itwgse.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/itwgse.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/itwgse.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/itwgse.com\/es\/wp-json\/wp\/v2\/comments?post=938"}],"version-history":[{"count":3,"href":"https:\/\/itwgse.com\/es\/wp-json\/wp\/v2\/posts\/938\/revisions"}],"predecessor-version":[{"id":14666,"href":"https:\/\/itwgse.com\/es\/wp-json\/wp\/v2\/posts\/938\/revisions\/14666"}],"wp:attachment":[{"href":"https:\/\/itwgse.com\/es\/wp-json\/wp\/v2\/media?parent=938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/itwgse.com\/es\/wp-json\/wp\/v2\/categories?post=938"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/itwgse.com\/es\/wp-json\/wp\/v2\/tags?post=938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}