{"id":28683,"date":"2026-02-24T14:04:56","date_gmt":"2026-02-24T13:04:56","guid":{"rendered":"https:\/\/itwgse.com\/temoignages-7400\/"},"modified":"2026-04-13T16:44:55","modified_gmt":"2026-04-13T14:44:55","slug":"temoignages-7400","status":"publish","type":"page","link":"https:\/\/itwgse.com\/fr\/temoignages-7400\/","title":{"rendered":"T\u00e9moignages-7400"},"content":{"rendered":"<div id=\"pl-28683\"  class=\"panel-layout\" ><div id=\"pg-28683-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-28683-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-28683-0-0-0\" class=\"so-panel widget widget_mtt-cover-section panel-first-child panel-last-child\" data-index=\"0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-mtt-cover-section so-widget-mtt-cover-section-base\"\n\t\t\t\n\t\t>\n<div class=\"mtt-cover-section-wrap compact extra-small\">\n\t<div class=\"mtt-cover-curve\">\n\t\t<img decoding=\"async\"  src=\"https:\/\/itwgse.com\/wp-content\/themes\/mtt-standard-theme\/assets\/img\/cover\/itwgse_cut.svg\">\t<\/div>\n    <div class=\"mtt-cover-compact-background object-fit\">\n                    <img decoding=\"async\"\n                src=\"https:\/\/itwgse.com\/wp-content\/uploads\/2020\/02\/ITWGSE_hero_7400.jpg\"\n                alt=\"\"\n                data-skip-lazy\n            >\n                            <\/div>\n    <div class=\"mtt-cover-compact-container\">\n        <div class=\"mtt-cover-section-text no-max-width\">\n            <h1>T\u00e9moignages - 7400 eGPU<\/h1>\n                                <div class=\"text\"><p>D\u00e9couvrez ce que les autres disent de l'eGPU aliment\u00e9 par batterie.<\/p>\n<\/div>\n                            <\/div>\n    <\/div>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-28683-1\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-28683-1-0\"  class=\"panel-grid-cell\" ><div id=\"panel-28683-1-0-0\" class=\"so-panel widget widget_mtt-one-col-text panel-first-child panel-last-child\" data-index=\"1\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-mtt-one-col-text so-widget-mtt-one-col-text-base\"\n\t\t\t\n\t\t>\n<div class=\"mtt-two-col-wrapper no-bottom-padding centered\">\n    <div class=\"mtt-two-col-container\">\n        <div class=\"mtt-two-col-content formatted_content\">\n\t\t\t                <h2>L'exp\u00e9rience utilisateur \u00e0 votre service !<\/h2>\n                        <div class=\"text-section one-col\">\n                <p>Vous souhaitez remplacer votre GPU actuel ? D\u00e9couvrez ce que les pairs disent de l'ITW GSE eGPU. <\/p>\n<p>Des t\u00e9moignages de clients \u00e0 votre service !<\/p>\n            <\/div>\n\n            \n                        <\/div>\n    <\/div>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-28683-2\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-28683-2-0\"  class=\"panel-grid-cell\" ><div id=\"panel-28683-2-0-0\" class=\"so-panel widget widget_mtt-text-image panel-first-child\" data-index=\"2\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-mtt-text-image so-widget-mtt-text-image-base\"\n\t\t\t\n\t\t>\n<div class=\"mtt-text-image-wrap flip\">\n        <!-- Content -->\n    <div class=\"mtt-text-image-container\">\n        <div class=\"mtt-text-image-col\">\n            <div class=\"mtt-text-image-content formatted_content\">\n                <div class=\"tagline\">T\u00e9moignage de l'a\u00e9roport de Milan Bergame, Italie<\/div>                <h2>Soutenir leur mission de d\u00e9veloppement durable<\/h2>\n                <p>L'a\u00e9roport de Milan Bergame s'efforce de devenir plus respectueux de l'environnement. L'utilisation d'eGPUs aliment\u00e9s par des batteries au lieu de GPUs aliment\u00e9s par des moteurs diesel permet \u00e0 l'a\u00e9roport d'\u00e9conomiser 120 tonnes de CO2 par Ann\u00e9e :. <\/p>\n<p><em>D\u00e9c\/2024<\/em><\/p>\n\n                                    <div class=\"button-wrap\">\n                                                    <a href=\"https:\/\/itwgse.com\/egpu-for-aviation\/milan-bergamo-airport-7400-egpu\/\" class=\"button\">\n                                Cas de lecture                            <\/a>\n                                            <\/div>\n                            <\/div>\n        <\/div>\n                    <div class=\"mtt-text-image-col video\">\n                <div class=\"mtt-text-image-content\">\n                                    \n                    \n                        <div class=\"mtt-text-image-video-wrap\">\n                            <div class=\"mtt-text-image-video-container\">\n                                <video preload=\"auto\" controls data-title=\"Bergamo video &#8211; English &#8211; final\" onpause=\"sendEvent('Pause', this)\" onplay=\"sendEvent('Play', this)\" onended=\"sendEvent('Ended', this)\">\n                                    <source type=\"video\/mp4\" src=\"https:\/\/itwgse.com\/wp-content\/uploads\/2024\/12\/Bergamo-video-English-final.mp4#t=0.1\">\n                                <\/video>\n                            <\/div>\n                        <\/div>\n\n                    \n                <\/div>\n            <\/div>\n            <\/div>\n<\/div>\n\n<script>\nfunction sendEvent(action, element) {\n    var videoTitle = jQuery(element).data('title');  \n\n    if (dataLayer && videoTitle) {\n        dataLayer.push({\n            'event': 'video',\n            'eventCategory': 'Video',\n            'eventAction': action,\n            'eventLabel': videoTitle\n        });\n    }\n    else if (ga && videoTitle) {\n        ga('send', 'event', 'Video', action, videoTitle);\n    }  \n}\n<\/script>\n<\/div><\/div><div id=\"panel-28683-2-0-1\" class=\"so-panel widget widget_mtt-text-image\" data-index=\"3\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-mtt-text-image so-widget-mtt-text-image-base\"\n\t\t\t\n\t\t>\n<div class=\"mtt-text-image-wrap no-bottom-padding less-top-padding\">\n        <!-- Content -->\n    <div class=\"mtt-text-image-container\">\n        <div class=\"mtt-text-image-col\">\n            <div class=\"mtt-text-image-content formatted_content\">\n                <div class=\"tagline\">T\u00e9moignage de SYST\u00c8ME (Med\u00e5t)<\/div>                <h2>Pourquoi l'arm\u00e9e utilise-t-elle des \u00e9quipements \u00e9lectriques ?<\/h2>\n                <p>Que pensez-vous \u00e9conomiser ?<\/p>\n<p>\"Le CO2, les NOx, les fum\u00e9es, le bruit et, bien s\u00fbr, l'\u00e9conomie des combustibles fossiles qui seraient normalement transport\u00e9s jusqu'\u00e0 la station\".<\/p>\n<p><strong>Max Waldron<br \/><\/strong>Service Delivery AGE at BAE Systems (Syst\u00e8me med\u00e5t)<\/p>\n<p><em>Janvier 2023<\/em><\/p>\n\n                                    <div class=\"button-wrap\">\n                                                    <a href=\"https:\/\/itwgse.com\/egpu-for-aviation\/why-the-military-is-using-electrical-equipment\/\" class=\"button\">\n                                Cas de lecture                            <\/a>\n                                            <\/div>\n                            <\/div>\n        <\/div>\n                    <div class=\"mtt-text-image-col video center\">\n                <div class=\"mtt-text-image-content\">\n                                    \n                    \n                        <div class=\"mtt-text-image-video-wrap\">\n                            <div class=\"mtt-text-image-video-container\">\n                                <video preload=\"auto\" controls data-title=\"BAE 7400 testimonial video\" onpause=\"sendEvent('Pause', this)\" onplay=\"sendEvent('Play', this)\" onended=\"sendEvent('Ended', this)\">\n                                    <source type=\"video\/mp4\" src=\"https:\/\/itwgse.com\/wp-content\/uploads\/2023\/01\/BAE-Monday-attempt.mp4#t=0.1\">\n                                <\/video>\n                            <\/div>\n                        <\/div>\n\n                    \n                <\/div>\n            <\/div>\n            <\/div>\n<\/div>\n\n<script>\nfunction sendEvent(action, element) {\n    var videoTitle = jQuery(element).data('title');  \n\n    if (dataLayer && videoTitle) {\n        dataLayer.push({\n            'event': 'video',\n            'eventCategory': 'Video',\n            'eventAction': action,\n            'eventLabel': videoTitle\n        });\n    }\n    else if (ga && videoTitle) {\n        ga('send', 'event', 'Video', action, videoTitle);\n    }  \n}\n<\/script>\n<\/div><\/div><div id=\"panel-28683-2-0-2\" class=\"so-panel widget widget_mtt-text-image\" data-index=\"4\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-mtt-text-image so-widget-mtt-text-image-base\"\n\t\t\t\n\t\t>\n<div class=\"mtt-text-image-wrap flip no-top-padding no-bottom-padding\">\n        <!-- Content -->\n    <div class=\"mtt-text-image-container\">\n        <div class=\"mtt-text-image-col\">\n            <div class=\"mtt-text-image-content formatted_content\">\n                <div class=\"tagline\">T\u00e9moignage de l'Airport Development Group<\/div>                <h2>Avantages environnementaux de l'a\u00e9roport international de Darwin<\/h2>\n                <p>ADG a adopt\u00e9 tr\u00e8s t\u00f4t des pratiques durables, son objectif \u00e9tant de parvenir \u00e0 des \u00e9missions nettes nulles d'ici \u00e0 2030.<\/p>\n<p>Nick Fewster, responsable de l'environnement et du d\u00e9veloppement durable, pr\u00e9sente quelques-uns des avantages environnementaux de la modernisation des ponts a\u00e9riens et de l'aire de trafic de l'a\u00e9roport international de Darwin.<\/p>\n<p><em>Mai\/2022<\/em><\/p>\n\n                                    <div class=\"button-wrap\">\n                                                    <a href=\"https:\/\/itwgse.com\/egpu-for-aviation\/environmental-benefits-darwin-international-airport\/\" class=\"button\">\n                                Cas de lecture                            <\/a>\n                                            <\/div>\n                            <\/div>\n        <\/div>\n                    <div class=\"mtt-text-image-col video center\">\n                <div class=\"mtt-text-image-content\">\n                                    \n                    \n                        <div class=\"mtt-text-image-video-wrap\">\n                            <div class=\"mtt-text-image-video-container\">\n                                <video preload=\"auto\" controls data-title=\"ADG &#8211; Darwin Airport video\" onpause=\"sendEvent('Pause', this)\" onplay=\"sendEvent('Play', this)\" onended=\"sendEvent('Ended', this)\">\n                                    <source type=\"video\/mp4\" src=\"https:\/\/itwgse.com\/wp-content\/uploads\/2022\/05\/ADG-Darwin-Airport-video.mp4#t=0.1\">\n                                <\/video>\n                            <\/div>\n                        <\/div>\n\n                    \n                <\/div>\n            <\/div>\n            <\/div>\n<\/div>\n\n<script>\nfunction sendEvent(action, element) {\n    var videoTitle = jQuery(element).data('title');  \n\n    if (dataLayer && videoTitle) {\n        dataLayer.push({\n            'event': 'video',\n            'eventCategory': 'Video',\n            'eventAction': action,\n            'eventLabel': videoTitle\n        });\n    }\n    else if (ga && videoTitle) {\n        ga('send', 'event', 'Video', action, videoTitle);\n    }  \n}\n<\/script>\n<\/div><\/div><div id=\"panel-28683-2-0-3\" class=\"so-panel widget widget_mtt-text-image\" data-index=\"5\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-mtt-text-image so-widget-mtt-text-image-base\"\n\t\t\t\n\t\t>\n<div class=\"mtt-text-image-wrap no-bottom-padding less-top-padding\">\n        <!-- Content -->\n    <div class=\"mtt-text-image-container\">\n        <div class=\"mtt-text-image-col\">\n            <div class=\"mtt-text-image-content formatted_content\">\n                <div class=\"tagline\">T\u00e9moignage de United Airlines<\/div>                <h2>L'environnement de la rampe est plus propre<\/h2>\n                <p>\"<em>Outre les questions \u00e0 grande \u00e9chelle relatives \u00e0 l'empreinte environnementale, le GSE \u00e9lectrique tel que le 7400 contribue \u00e0 maintenir l'environnement de l'aire de trafic plus propre, et donc l'environnement de la cabine plus propre<\/em>\".<\/p>\n<p>\u00a0<\/p>\n<p><strong>Tim Fox <\/strong><br \/>Responsable des projets d'ing\u00e9nierie et de maintenance des installations<br \/>United Airlines<\/p>\n<p><em>Nov\/2021<\/em><\/p>\n\n                            <\/div>\n        <\/div>\n                    <div class=\"mtt-text-image-col img center\">\n                <div class=\"mtt-text-image-content\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1920\" src=\"https:\/\/itwgse.com\/wp-content\/uploads\/2021\/12\/Tim-Fox-2021-Inter-Airport-9-scaled.jpeg\" class=\"attachment-full size-full\" alt=\"7400 customer voice testimonial\" srcset=\"https:\/\/itwgse.com\/wp-content\/uploads\/2021\/12\/Tim-Fox-2021-Inter-Airport-9-scaled.jpeg 2560w, https:\/\/itwgse.com\/wp-content\/uploads\/2021\/12\/Tim-Fox-2021-Inter-Airport-9-scaled-300x225.jpeg 300w, https:\/\/itwgse.com\/wp-content\/uploads\/2021\/12\/Tim-Fox-2021-Inter-Airport-9-scaled-1024x768.jpeg 1024w, https:\/\/itwgse.com\/wp-content\/uploads\/2021\/12\/Tim-Fox-2021-Inter-Airport-9-scaled-267x200.jpeg 267w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/>                \n                    \n                    \n                <\/div>\n            <\/div>\n            <\/div>\n<\/div>\n\n<script>\nfunction sendEvent(action, element) {\n    var videoTitle = jQuery(element).data('title');  \n\n    if (dataLayer && videoTitle) {\n        dataLayer.push({\n            'event': 'video',\n            'eventCategory': 'Video',\n            'eventAction': action,\n            'eventLabel': videoTitle\n        });\n    }\n    else if (ga && videoTitle) {\n        ga('send', 'event', 'Video', action, videoTitle);\n    }  \n}\n<\/script>\n<\/div><\/div><div id=\"panel-28683-2-0-4\" class=\"so-panel widget widget_mtt-text-image\" data-index=\"6\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-mtt-text-image so-widget-mtt-text-image-base\"\n\t\t\t\n\t\t>\n<div class=\"mtt-text-image-wrap flip no-top-padding no-bottom-padding\">\n        <!-- Content -->\n    <div class=\"mtt-text-image-container\">\n        <div class=\"mtt-text-image-col\">\n            <div class=\"mtt-text-image-content formatted_content\">\n                <div class=\"tagline\">T\u00e9moignage de TAG Maintenance Services<\/div>                <h2>Premier eGPU pour l'aviation d'affaires europ\u00e9enne<\/h2>\n                <p><i>\"<\/i><i>Nous avons soumis l'eGPU d'ITW \u00e0 des essais approfondis et nous avons \u00e9t\u00e9 extr\u00eamement impressionn\u00e9s par son efficacit\u00e9 et sa robustesse. <\/i> <i>la polyvalence. Les  <\/i><i>L'unit\u00e9 peut effectuer plusieurs rotations avant d'avoir besoin d'\u00eatre recharg\u00e9e, et son silence et son fonctionnement sans pollution la rendent populaire aupr\u00e8s des employ\u00e9s et des op\u00e9rateurs\".<\/i><\/p>\n<p><b>Cyrille Pillet<br \/><\/b>Vice-pr\u00e9sident<br \/>Maintenance Operations<br \/>TAG Maintenance Services<\/p>\n<p><em>Nov\/2021<\/em><\/p>\n\n                            <\/div>\n        <\/div>\n                    <div class=\"mtt-text-image-col img center\">\n                <div class=\"mtt-text-image-content\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"1281\" height=\"854\" src=\"https:\/\/itwgse.com\/wp-content\/uploads\/2021\/11\/TAG-Maintenance-Services_First-eGPU-introduced-to-Switzerland.jpeg\" class=\"attachment-full size-full\" alt=\"itw gse 7400 eGPU testimonial\" srcset=\"https:\/\/itwgse.com\/wp-content\/uploads\/2021\/11\/TAG-Maintenance-Services_First-eGPU-introduced-to-Switzerland.jpeg 1281w, https:\/\/itwgse.com\/wp-content\/uploads\/2021\/11\/TAG-Maintenance-Services_First-eGPU-introduced-to-Switzerland-300x200.jpeg 300w, https:\/\/itwgse.com\/wp-content\/uploads\/2021\/11\/TAG-Maintenance-Services_First-eGPU-introduced-to-Switzerland-1024x683.jpeg 1024w\" sizes=\"auto, (max-width: 1281px) 100vw, 1281px\" \/>                \n                    \n                    \n                <\/div>\n            <\/div>\n            <\/div>\n<\/div>\n\n<script>\nfunction sendEvent(action, element) {\n    var videoTitle = jQuery(element).data('title');  \n\n    if (dataLayer && videoTitle) {\n        dataLayer.push({\n            'event': 'video',\n            'eventCategory': 'Video',\n            'eventAction': action,\n            'eventLabel': videoTitle\n        });\n    }\n    else if (ga && videoTitle) {\n        ga('send', 'event', 'Video', action, videoTitle);\n    }  \n}\n<\/script>\n<\/div><\/div><div id=\"panel-28683-2-0-5\" class=\"so-panel widget widget_mtt-text-image\" data-index=\"7\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-mtt-text-image so-widget-mtt-text-image-base\"\n\t\t\t\n\t\t>\n<div class=\"mtt-text-image-wrap no-top-padding no-bottom-padding\">\n        <!-- Content -->\n    <div class=\"mtt-text-image-container\">\n        <div class=\"mtt-text-image-col\">\n            <div class=\"mtt-text-image-content formatted_content\">\n                <div class=\"tagline\">T\u00e9moignage de TOP GSE<\/div>                <h2>TOP GSE recommande l'ITW GSE 7400 eGPU pendant le FAT<\/h2>\n                <p>Lors d'un FAT dans nos installations danoises en d\u00e9cembre 2019, TOP GSE a test\u00e9 l'eGPU aliment\u00e9 par batterie et est arriv\u00e9 \u00e0 la conclusion d'acheter et de recommander l'unit\u00e9.<\/p>\n<p>TOP GSE est ainsi le premier sur le march\u00e9 espagnol \u00e0 mettre en service un convertisseur redresseur ( 28DC) aliment\u00e9 par batterie dans les op\u00e9rations d'assistance au sol espagnoles.<\/p>\n<p>Nous avons le plaisir de vous pr\u00e9senter <strong>Mateo Salamanca Sanchez<\/strong>, directeur g\u00e9n\u00e9ral de TOP GSE :<\/p>\n<p><em>\/D\u00e9cembre 2019<\/em><\/p>\n\n                                    <div class=\"button-wrap\">\n                                                    <a href=\"https:\/\/itwgse.com\/egpu-for-aviation\/top-gse-recommends-7400-egpu-fat\/\" class=\"button\">\n                                Cas de lecture                            <\/a>\n                                            <\/div>\n                            <\/div>\n        <\/div>\n                    <div class=\"mtt-text-image-col video\">\n                <div class=\"mtt-text-image-content\">\n                                    \n                    \n                        <div class=\"mtt-text-image-video-wrap\">\n                            <div class=\"mtt-text-image-video-container\">\n                                <video preload=\"auto\" controls data-title=\"TOP GSE ITW GSE 7400 &#8211; English\" onpause=\"sendEvent('Pause', this)\" onplay=\"sendEvent('Play', this)\" onended=\"sendEvent('Ended', this)\">\n                                    <source type=\"video\/mp4\" src=\"https:\/\/itwgse.com\/wp-content\/uploads\/2020\/01\/TOP-GSE-ITW-GSE-7400-English.mp4#t=0.1\">\n                                <\/video>\n                            <\/div>\n                        <\/div>\n\n                    \n                <\/div>\n            <\/div>\n            <\/div>\n<\/div>\n\n<script>\nfunction sendEvent(action, element) {\n    var videoTitle = jQuery(element).data('title');  \n\n    if (dataLayer && videoTitle) {\n        dataLayer.push({\n            'event': 'video',\n            'eventCategory': 'Video',\n            'eventAction': action,\n            'eventLabel': videoTitle\n        });\n    }\n    else if (ga && videoTitle) {\n        ga('send', 'event', 'Video', action, videoTitle);\n    }  \n}\n<\/script>\n<\/div><\/div><div id=\"panel-28683-2-0-6\" class=\"so-panel widget widget_mtt-text-image\" data-index=\"8\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-mtt-text-image so-widget-mtt-text-image-base\"\n\t\t\t\n\t\t>\n<div class=\"mtt-text-image-wrap flip no-top-padding less-bottom-padding\">\n        <!-- Content -->\n    <div class=\"mtt-text-image-container\">\n        <div class=\"mtt-text-image-col\">\n            <div class=\"mtt-text-image-content formatted_content\">\n                <div class=\"tagline\">T\u00e9moignage des Valid\u00e9(e)s du service Viggo<\/div>                <h2>Utilisation de l'eGPU<\/h2>\n                <p>Viggo Service Enablers a test\u00e9 l'ITW GSE 7400 eGPU \u00e0 l'a\u00e9roport d'Eindhoven, aux Pays-Bas.<\/p>\n<p><strong>Jelmer Melissen<\/strong>, responsable du d\u00e9veloppement commercial chez Viggo Service Enablers, d\u00e9clare : \"<em>L'unit\u00e9 7400 est tr\u00e8s facile \u00e0 utiliser gr\u00e2ce \u00e0 l'\u00e9cran. Cela r\u00e9duit le temps de formation des op\u00e9rateurs. <\/em><\/p>\n<p>Le responsable de la qualit\u00e9 et de la s\u00e9curit\u00e9 chez Viggo Valid\u00e9, <strong>Wout Ruijs<\/strong>, d\u00e9clare : \"<em>L'eGPU offre un meilleur environnement de travail au personnel, aux \u00e9quipages et aux passagers qu'un moteur \u00e0 combustion. Un autre avantage est le silence\". <\/em><\/p>\n<p><em>\/Juin 2019<\/em><\/p>\n\n                                    <div class=\"button-wrap\">\n                                                    <a href=\"https:\/\/itwgse.com\/egpu-for-aviation\/viggo-service-enablers-tests-the-itw-gse-7400-egpu-in-eindhoven-airport\/\" class=\"button\">\n                                Cas de lecture                            <\/a>\n                                            <\/div>\n                            <\/div>\n        <\/div>\n                    <div class=\"mtt-text-image-col video\">\n                <div class=\"mtt-text-image-content\">\n                                    \n                    \n                        <div class=\"mtt-text-image-video-wrap\">\n                            <div class=\"mtt-text-image-video-container\">\n                                <video preload=\"auto\" controls data-title=\"ITWGSE-VIGGO_Service_Enablers\" onpause=\"sendEvent('Pause', this)\" onplay=\"sendEvent('Play', this)\" onended=\"sendEvent('Ended', this)\">\n                                    <source type=\"video\/mp4\" src=\"https:\/\/itwgse.com\/wp-content\/uploads\/2020\/01\/ITWGSE-VIGGO_Service_Enablers.mp4#t=0.1\">\n                                <\/video>\n                            <\/div>\n                        <\/div>\n\n                    \n                <\/div>\n            <\/div>\n            <\/div>\n<\/div>\n\n<script>\nfunction sendEvent(action, element) {\n    var videoTitle = jQuery(element).data('title');  \n\n    if (dataLayer && videoTitle) {\n        dataLayer.push({\n            'event': 'video',\n            'eventCategory': 'Video',\n            'eventAction': action,\n            'eventLabel': videoTitle\n        });\n    }\n    else if (ga && videoTitle) {\n        ga('send', 'event', 'Video', action, videoTitle);\n    }  \n}\n<\/script>\n<\/div><\/div><div id=\"panel-28683-2-0-7\" class=\"so-panel widget widget_mtt-text-image panel-last-child\" data-index=\"9\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-mtt-text-image so-widget-mtt-text-image-base\"\n\t\t\t\n\t\t>\n<div class=\"mtt-text-image-wrap no-top-padding less-bottom-padding\">\n        <!-- Content -->\n    <div class=\"mtt-text-image-container\">\n        <div class=\"mtt-text-image-col\">\n            <div class=\"mtt-text-image-content formatted_content\">\n                <div class=\"tagline\">Le t\u00e9moignage de RATE Australia Pty. Ltd.<\/div>                <h2>L'a\u00e9roport de Brisbane se met au vert avec l'ITW GSE 7400 eGPU !<\/h2>\n                <p>Partout dans le monde, des initiatives sont prises pour am\u00e9liorer l'environnement, et l'a\u00e9roport de Brisbane en est un nouvel exemple.<\/p>\n<p>Dans ce t\u00e9moignage vid\u00e9o, vous voyez Peter Reidy de RATE Australia Pty. Ltd. qui est venu au Danemark pour tester l'eGPU avant qu'il ne soit envoy\u00e9 \u00e0 l'a\u00e9roport de Brisbane. <\/p>\n<p><em>\/Novembre 2018.<\/em><\/p>\n\n                                    <div class=\"button-wrap\">\n                                                    <a href=\"https:\/\/itwgse.com\/egpu-for-aviation\/brisbane-airport-7400-egpu\/\" class=\"button\">\n                                Cas de lecture                            <\/a>\n                                            <\/div>\n                            <\/div>\n        <\/div>\n                    <div class=\"mtt-text-image-col video\">\n                <div class=\"mtt-text-image-content\">\n                                    \n                    \n                        <div class=\"mtt-text-image-video-wrap\">\n                            <div class=\"mtt-text-image-video-container\">\n                                <video preload=\"auto\" controls data-title=\"ITWGSE-RATE_Australia-7400eGPU\" onpause=\"sendEvent('Pause', this)\" onplay=\"sendEvent('Play', this)\" onended=\"sendEvent('Ended', this)\">\n                                    <source type=\"video\/mp4\" src=\"https:\/\/itwgse.com\/wp-content\/uploads\/2020\/01\/ITWGSE-RATE_Australia.mp4#t=0.1\">\n                                <\/video>\n                            <\/div>\n                        <\/div>\n\n                    \n                <\/div>\n            <\/div>\n            <\/div>\n<\/div>\n\n<script>\nfunction sendEvent(action, element) {\n    var videoTitle = jQuery(element).data('title');  \n\n    if (dataLayer && videoTitle) {\n        dataLayer.push({\n            'event': 'video',\n            'eventCategory': 'Video',\n            'eventAction': action,\n            'eventLabel': videoTitle\n        });\n    }\n    else if (ga && videoTitle) {\n        ga('send', 'event', 'Video', action, videoTitle);\n    }  \n}\n<\/script>\n<\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>T\u00e9moignages &#8211; 7400 eGPU D\u00e9couvrez ce que les autres disent de l&rsquo;eGPU aliment\u00e9 par batterie. L&rsquo;exp\u00e9rience utilisateur \u00e0 votre service ! Vous souhaitez remplacer&#8230;<\/p>\n","protected":false},"author":11,"featured_media":0,"parent":0,"menu_order":231,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"class_list":["post-28683","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>T\u00e9moignages - ITW GSE 7400 eGPU | ITW GSE - Ground Power Units (en relation to 28 VDC)<\/title>\n<meta name=\"description\" content=\"T\u00e9moignages sur le 7400 eGPU. Sachez ce que les utilisateurs actuels disent de l&#039;ITW GSE 7400, convertisseur redresseur ( relation VDC).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/itwgse.com\/fr\/temoignages-7400\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"T\u00e9moignages - ITW GSE 7400 eGPU | ITW GSE - Ground Power Units (en relation to 28 VDC)\" \/>\n<meta property=\"og:description\" content=\"T\u00e9moignages sur le 7400 eGPU. Sachez ce que les utilisateurs actuels disent de l&#039;ITW GSE 7400, convertisseur redresseur ( relation VDC).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/itwgse.com\/fr\/temoignages-7400\/\" \/>\n<meta property=\"og:site_name\" content=\"ITW GSE\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ITWGSE\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-13T14:44:55+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/itwgse.com\/fr\/temoignages-7400\/\",\"url\":\"https:\/\/itwgse.com\/fr\/temoignages-7400\/\",\"name\":\"T\u00e9moignages - ITW GSE 7400 eGPU | ITW GSE - Ground Power Units (en relation to 28 VDC)\",\"isPartOf\":{\"@id\":\"https:\/\/itwgse.com\/#website\"},\"datePublished\":\"2026-02-24T13:04:56+00:00\",\"dateModified\":\"2026-04-13T14:44:55+00:00\",\"description\":\"T\u00e9moignages sur le 7400 eGPU. Sachez ce que les utilisateurs actuels disent de l'ITW GSE 7400, convertisseur redresseur ( relation VDC).\",\"breadcrumb\":{\"@id\":\"https:\/\/itwgse.com\/fr\/temoignages-7400\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/itwgse.com\/fr\/temoignages-7400\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/itwgse.com\/fr\/temoignages-7400\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/itwgse.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"T\u00e9moignages-7400\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/itwgse.com\/#website\",\"url\":\"https:\/\/itwgse.com\/\",\"name\":\"ITW GSE\",\"description\":\"It&#039;s all about connections\",\"publisher\":{\"@id\":\"https:\/\/itwgse.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/itwgse.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/itwgse.com\/#organization\",\"name\":\"ITW GSE\",\"url\":\"https:\/\/itwgse.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/itwgse.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/itwgse.com\/wp-content\/uploads\/2018\/11\/logo.png\",\"contentUrl\":\"https:\/\/itwgse.com\/wp-content\/uploads\/2018\/11\/logo.png\",\"width\":302,\"height\":237,\"caption\":\"ITW GSE\"},\"image\":{\"@id\":\"https:\/\/itwgse.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/ITWGSE\/\",\"https:\/\/www.linkedin.com\/company\/itw-gse\/\",\"https:\/\/www.youtube.com\/channel\/UCTUIMvyaOPfYIqzP8enZ8yw\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"T\u00e9moignages - ITW GSE 7400 eGPU | ITW GSE - Ground Power Units (en relation to 28 VDC)","description":"T\u00e9moignages sur le 7400 eGPU. Sachez ce que les utilisateurs actuels disent de l'ITW GSE 7400, convertisseur redresseur ( relation VDC).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/itwgse.com\/fr\/temoignages-7400\/","og_locale":"fr_FR","og_type":"article","og_title":"T\u00e9moignages - ITW GSE 7400 eGPU | ITW GSE - Ground Power Units (en relation to 28 VDC)","og_description":"T\u00e9moignages sur le 7400 eGPU. Sachez ce que les utilisateurs actuels disent de l'ITW GSE 7400, convertisseur redresseur ( relation VDC).","og_url":"https:\/\/itwgse.com\/fr\/temoignages-7400\/","og_site_name":"ITW GSE","article_publisher":"https:\/\/www.facebook.com\/ITWGSE\/","article_modified_time":"2026-04-13T14:44:55+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/itwgse.com\/fr\/temoignages-7400\/","url":"https:\/\/itwgse.com\/fr\/temoignages-7400\/","name":"T\u00e9moignages - ITW GSE 7400 eGPU | ITW GSE - Ground Power Units (en relation to 28 VDC)","isPartOf":{"@id":"https:\/\/itwgse.com\/#website"},"datePublished":"2026-02-24T13:04:56+00:00","dateModified":"2026-04-13T14:44:55+00:00","description":"T\u00e9moignages sur le 7400 eGPU. Sachez ce que les utilisateurs actuels disent de l'ITW GSE 7400, convertisseur redresseur ( relation VDC).","breadcrumb":{"@id":"https:\/\/itwgse.com\/fr\/temoignages-7400\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/itwgse.com\/fr\/temoignages-7400\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/itwgse.com\/fr\/temoignages-7400\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/itwgse.com\/fr\/"},{"@type":"ListItem","position":2,"name":"T\u00e9moignages-7400"}]},{"@type":"WebSite","@id":"https:\/\/itwgse.com\/#website","url":"https:\/\/itwgse.com\/","name":"ITW GSE","description":"It&#039;s all about connections","publisher":{"@id":"https:\/\/itwgse.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/itwgse.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/itwgse.com\/#organization","name":"ITW GSE","url":"https:\/\/itwgse.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/itwgse.com\/#\/schema\/logo\/image\/","url":"https:\/\/itwgse.com\/wp-content\/uploads\/2018\/11\/logo.png","contentUrl":"https:\/\/itwgse.com\/wp-content\/uploads\/2018\/11\/logo.png","width":302,"height":237,"caption":"ITW GSE"},"image":{"@id":"https:\/\/itwgse.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ITWGSE\/","https:\/\/www.linkedin.com\/company\/itw-gse\/","https:\/\/www.youtube.com\/channel\/UCTUIMvyaOPfYIqzP8enZ8yw"]}]}},"_links":{"self":[{"href":"https:\/\/itwgse.com\/fr\/wp-json\/wp\/v2\/pages\/28683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/itwgse.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/itwgse.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/itwgse.com\/fr\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/itwgse.com\/fr\/wp-json\/wp\/v2\/comments?post=28683"}],"version-history":[{"count":1,"href":"https:\/\/itwgse.com\/fr\/wp-json\/wp\/v2\/pages\/28683\/revisions"}],"predecessor-version":[{"id":45642,"href":"https:\/\/itwgse.com\/fr\/wp-json\/wp\/v2\/pages\/28683\/revisions\/45642"}],"wp:attachment":[{"href":"https:\/\/itwgse.com\/fr\/wp-json\/wp\/v2\/media?parent=28683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}