{"id":45509,"date":"2026-03-18T15:39:31","date_gmt":"2026-03-18T14:39:31","guid":{"rendered":"https:\/\/itwgse.com\/2400-power-coil\/"},"modified":"2026-03-18T15:39:31","modified_gmt":"2026-03-18T14:39:31","slug":"2400-power-coil","status":"publish","type":"page","link":"https:\/\/itwgse.com\/fr\/2400-power-coil\/","title":{"rendered":"2400 Power Coil"},"content":{"rendered":"<div id=\"pl-45509\"  class=\"panel-layout\" ><div id=\"pg-45509-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-45509-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-45509-0-0-0\" class=\"so-panel widget widget_mtt-cover-section panel-first-child\" data-index=\"0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-mtt-cover-section so-widget-mtt-cover-section-base\"\n\t\t\t\n\t\t>\n<div class=\"mtt-cover-section-wrap compact extra-small\">\n\t<div class=\"mtt-cover-curve\">\n\t\t<img decoding=\"async\"  src=\"https:\/\/itwgse.com\/wp-content\/themes\/mtt-standard-theme\/assets\/img\/cover\/itwgse_cut.svg\">\t<\/div>\n    <div class=\"mtt-cover-compact-background object-fit overlay\">\n                            <\/div>\n    <div class=\"mtt-cover-compact-container\">\n        <div class=\"mtt-cover-section-text no-max-width\">\n            <h1>2400 Power Coil Instruction<\/h1>\n                                <div class=\"text\"><p><span lang=\"en-US\">Retrouvez des vid\u00e9os sur la Power Coil GSE d'ITW, concernant le remplacement de la puce d'identification, de la carte de contr\u00f4le et du c\u00e2ble de l'avion.<\/span><\/p>\n<\/div>\n                            <\/div>\n    <\/div>\n<\/div>\n<\/div><\/div><div id=\"panel-45509-0-0-1\" class=\"so-panel widget widget_mtt-video-grid\" data-index=\"1\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-mtt-video-grid so-widget-mtt-video-grid-base\"\n\t\t\t\n\t\t>\n<div class=\"videos\">\n                <div class=\"video instruction-vid-click hideborder\" data-id=\"kTYGfsCKK5w\">\n                <div class=\"img\">\n                    <img decoding=\"async\" src=\"http:\/\/img.youtube.com\/vi\/kTYGfsCKK5w\/hqdefault.jpg\"\/>\n                <\/div>\n                <h2>Remplacement de la puce d'identification dans la Power Coil 2400<\/h2>\n            <\/div>\n            <span><\/span>\n                    <div class=\"video instruction-vid-click hideborder\" data-id=\"NsRpgPDIwQI\">\n                <div class=\"img\">\n                    <img decoding=\"async\" src=\"http:\/\/img.youtube.com\/vi\/NsRpgPDIwQI\/hqdefault.jpg\"\/>\n                <\/div>\n                <h2>Remplacement de la carte de contr\u00f4le dans l'ITW GSE 2400 Power Coil<\/h2>\n            <\/div>\n            <span><\/span>\n                    <div class=\"video instruction-vid-click hideborder\" data-id=\"LBrYwQ5atAA\">\n                <div class=\"img\">\n                    <img decoding=\"async\" src=\"http:\/\/img.youtube.com\/vi\/LBrYwQ5atAA\/hqdefault.jpg\"\/>\n                <\/div>\n                <h2>  Remplacement du c\u00e2ble d'avion 2400 Power Coil<\/h2>\n            <\/div>\n            <span><\/span>\n        <\/div>\n\n<div class=\"vid-overlay\">\n    <div class=\"exit\"><\/div>\n    <svg id=\"preloader\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 200 200\"><defs><style>.cls-1{fill:none;stroke:#e6e6e6;stroke-miterlimit:10;stroke-width:10px;}.cls-2{fill:#00b0eb;}<\/style><\/defs><title>preloader<\/title><circle id=\"circle\" class=\"cls-1\" cx=\"100\" cy=\"100\" r=\"73\"\/><path id=\"flight\" class=\"cls-2\" d=\"M100,27s62,1,68,69l-18-7v4l18,15-2,12s-1,4.33,2,5.67,6-3.67,6-3.67,2-2,3-12l19-15V91l-18,6S178,32,100,27Z\"\/><\/svg>\n\t<div class=\"player\">\n\t\t<div class=\"cookieconsent-message cookieconsent-optout-marketing\">\n\t\t\t<h4>Please accept <span>marketing-cookies<\/span> to watch this video<\/h4>\n\t\t\t<a href=\"javascript:Cookiebot.renew()\" class=\"button white\">Change Cookie Preferences<\/a>\n\t\t<\/div>\n    <\/div>\n<\/div><\/div><\/div><div id=\"panel-45509-0-0-2\" class=\"so-panel widget widget_mtt-customer-support panel-last-child\" data-index=\"2\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-mtt-customer-support so-widget-mtt-customer-support-base\"\n\t\t\t\n\t\t>\n<div class=\"mtt-text-image-wrap less-top-padding less-bottom-padding grey-bg\">\n        <!-- Content -->\n    <div class=\"mtt-text-image-container\">\n        <div class=\"mtt-text-image-col\">\n            <div class=\"mtt-text-image-content formatted_content\">\n                                <h2>Assistance client\u00e8le<\/h2>\n                <p><strong>Comment pouvons-nous vous aider\u00a0?<\/strong><\/p>\n<p>Besoin de sch\u00e9mas, de listes de pi\u00e8ces d\u00e9tach\u00e9es ou de tutoriels vid\u00e9o\u00a0? Cliquez sur le bouton \u00ab\u00a0Assistance produit\u00a0\u00bb.<\/p>\n<p>Des questions pour l\u2019assistance client\u00e8le\u00a0? Cliquez sur le bouton \u00ab\u00a0Contacter l\u2019assistance client\u00e8le\u00a0\u00bb.<\/p>\n<p>Si votre question concerne un produit sp\u00e9cifique, veuillez indiquer son num\u00e9ro de s\u00e9rie.<\/p>\n\n                                    <div class=\"button-wrap\">\n                                                    <a href=\"https:\/\/itwgse.com\/fr\/soutien-et-service\/\" class=\"button\">\n                                Assistance produit                            <\/a>\n                                                    <a href=\"https:\/\/itwgse.com\/fr\/contact\/\" class=\"button\">\n                                Contacter l\u2019assistance client\u00e8le                            <\/a>\n                                            <\/div>\n                            <\/div>\n        <\/div>\n                    <div class=\"mtt-text-image-col img center\">\n                <div class=\"mtt-text-image-content\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"1800\" height=\"1023\" src=\"https:\/\/itwgse.com\/wp-content\/uploads\/2018\/06\/ITWGSE_hero_cleanest-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/itwgse.com\/wp-content\/uploads\/2018\/06\/ITWGSE_hero_cleanest-1.jpg 1800w, https:\/\/itwgse.com\/wp-content\/uploads\/2018\/06\/ITWGSE_hero_cleanest-1-300x171.jpg 300w, https:\/\/itwgse.com\/wp-content\/uploads\/2018\/06\/ITWGSE_hero_cleanest-1-1024x582.jpg 1024w\" sizes=\"auto, (max-width: 1800px) 100vw, 1800px\" \/>                \n                    \n                    \n                <\/div>\n            <\/div>\n            <\/div>\n<\/div>\n\n<script>\nfunction sendEvent(action, element) {\n    var videoTitle = jQuery(element).data('title');  \n\n    if (dataLayer && videoTitle) {\n        dataLayer.push({\n            'event': 'video',\n            'eventCategory': 'Video',\n            'eventAction': action,\n            'eventLabel': videoTitle\n        });\n    }\n    else if (ga && videoTitle) {\n        ga('send', 'event', 'Video', action, videoTitle);\n    }  \n}\n<\/script>\n<\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>2400 Power Coil Instruction Retrouvez des vid\u00e9os sur la Power Coil GSE d&rsquo;ITW, concernant le remplacement de la puce d&rsquo;identification, de la carte de&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":243,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"class_list":["post-45509","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>2400 Power Coil Instruction - Vid\u00e9os d&#039;instruction | ITW GSE<\/title>\n<meta name=\"description\" content=\"ITW GSE a publi\u00e9 des vid\u00e9os d&#039;instruction sur les Power Coil 2400, concernant le remplacement de la puce d&#039;identification, de la carte de contr\u00f4le et du c\u00e2ble de l&#039;avion.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/itwgse.com\/fr\/2400-power-coil\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2400 Power Coil Instruction - Vid\u00e9os d&#039;instruction | ITW GSE\" \/>\n<meta property=\"og:description\" content=\"ITW GSE a publi\u00e9 des vid\u00e9os d&#039;instruction sur les Power Coil 2400, concernant le remplacement de la puce d&#039;identification, de la carte de contr\u00f4le et du c\u00e2ble de l&#039;avion.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/itwgse.com\/fr\/2400-power-coil\/\" \/>\n<meta property=\"og:site_name\" content=\"ITW GSE\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ITWGSE\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/itwgse.com\/fr\/2400-power-coil\/\",\"url\":\"https:\/\/itwgse.com\/fr\/2400-power-coil\/\",\"name\":\"2400 Power Coil Instruction - Vid\u00e9os d'instruction | ITW GSE\",\"isPartOf\":{\"@id\":\"https:\/\/itwgse.com\/#website\"},\"datePublished\":\"2026-03-18T14:39:31+00:00\",\"description\":\"ITW GSE a publi\u00e9 des vid\u00e9os d'instruction sur les Power Coil 2400, concernant le remplacement de la puce d'identification, de la carte de contr\u00f4le et du c\u00e2ble de l'avion.\",\"breadcrumb\":{\"@id\":\"https:\/\/itwgse.com\/fr\/2400-power-coil\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/itwgse.com\/fr\/2400-power-coil\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/itwgse.com\/fr\/2400-power-coil\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/itwgse.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"2400 Power Coil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/itwgse.com\/#website\",\"url\":\"https:\/\/itwgse.com\/\",\"name\":\"ITW GSE\",\"description\":\"It&#039;s all about connections\",\"publisher\":{\"@id\":\"https:\/\/itwgse.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/itwgse.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/itwgse.com\/#organization\",\"name\":\"ITW GSE\",\"url\":\"https:\/\/itwgse.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/itwgse.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/itwgse.com\/wp-content\/uploads\/2018\/11\/logo.png\",\"contentUrl\":\"https:\/\/itwgse.com\/wp-content\/uploads\/2018\/11\/logo.png\",\"width\":302,\"height\":237,\"caption\":\"ITW GSE\"},\"image\":{\"@id\":\"https:\/\/itwgse.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/ITWGSE\/\",\"https:\/\/www.linkedin.com\/company\/itw-gse\/\",\"https:\/\/www.youtube.com\/channel\/UCTUIMvyaOPfYIqzP8enZ8yw\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"2400 Power Coil Instruction - Vid\u00e9os d'instruction | ITW GSE","description":"ITW GSE a publi\u00e9 des vid\u00e9os d'instruction sur les Power Coil 2400, concernant le remplacement de la puce d'identification, de la carte de contr\u00f4le et du c\u00e2ble de l'avion.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/itwgse.com\/fr\/2400-power-coil\/","og_locale":"fr_FR","og_type":"article","og_title":"2400 Power Coil Instruction - Vid\u00e9os d'instruction | ITW GSE","og_description":"ITW GSE a publi\u00e9 des vid\u00e9os d'instruction sur les Power Coil 2400, concernant le remplacement de la puce d'identification, de la carte de contr\u00f4le et du c\u00e2ble de l'avion.","og_url":"https:\/\/itwgse.com\/fr\/2400-power-coil\/","og_site_name":"ITW GSE","article_publisher":"https:\/\/www.facebook.com\/ITWGSE\/","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/itwgse.com\/fr\/2400-power-coil\/","url":"https:\/\/itwgse.com\/fr\/2400-power-coil\/","name":"2400 Power Coil Instruction - Vid\u00e9os d'instruction | ITW GSE","isPartOf":{"@id":"https:\/\/itwgse.com\/#website"},"datePublished":"2026-03-18T14:39:31+00:00","description":"ITW GSE a publi\u00e9 des vid\u00e9os d'instruction sur les Power Coil 2400, concernant le remplacement de la puce d'identification, de la carte de contr\u00f4le et du c\u00e2ble de l'avion.","breadcrumb":{"@id":"https:\/\/itwgse.com\/fr\/2400-power-coil\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/itwgse.com\/fr\/2400-power-coil\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/itwgse.com\/fr\/2400-power-coil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/itwgse.com\/fr\/"},{"@type":"ListItem","position":2,"name":"2400 Power Coil"}]},{"@type":"WebSite","@id":"https:\/\/itwgse.com\/#website","url":"https:\/\/itwgse.com\/","name":"ITW GSE","description":"It&#039;s all about connections","publisher":{"@id":"https:\/\/itwgse.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/itwgse.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/itwgse.com\/#organization","name":"ITW GSE","url":"https:\/\/itwgse.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/itwgse.com\/#\/schema\/logo\/image\/","url":"https:\/\/itwgse.com\/wp-content\/uploads\/2018\/11\/logo.png","contentUrl":"https:\/\/itwgse.com\/wp-content\/uploads\/2018\/11\/logo.png","width":302,"height":237,"caption":"ITW GSE"},"image":{"@id":"https:\/\/itwgse.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ITWGSE\/","https:\/\/www.linkedin.com\/company\/itw-gse\/","https:\/\/www.youtube.com\/channel\/UCTUIMvyaOPfYIqzP8enZ8yw"]}]}},"_links":{"self":[{"href":"https:\/\/itwgse.com\/fr\/wp-json\/wp\/v2\/pages\/45509","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/itwgse.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/itwgse.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/itwgse.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/itwgse.com\/fr\/wp-json\/wp\/v2\/comments?post=45509"}],"version-history":[{"count":0,"href":"https:\/\/itwgse.com\/fr\/wp-json\/wp\/v2\/pages\/45509\/revisions"}],"wp:attachment":[{"href":"https:\/\/itwgse.com\/fr\/wp-json\/wp\/v2\/media?parent=45509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}