{"id":24518,"date":"2023-10-31T13:56:52","date_gmt":"2023-10-31T12:56:52","guid":{"rendered":"https:\/\/itwgse.com\/?p=24518"},"modified":"2023-10-31T13:56:52","modified_gmt":"2023-10-31T12:56:52","slug":"itw-patent-society-award-dinner-2023","status":"publish","type":"post","link":"https:\/\/itwgse.com\/fr\/news\/itw-patent-society-award-dinner-2023\/","title":{"rendered":"ITW Patent Society Award Dinner 2023"},"content":{"rendered":"<p><strong>&#8230;all with the focus on honoring present and past innovators at ITW.\u00a0<\/strong><br \/>\nWe are pleased to tell that our R&amp;D team members have been rewarded for their great job with the Pre-Conditioned Air (PCA) patent. The reward was handed over during the &lsquo;ITW Patent Society Dinner 2023&rsquo; event in Germany, where a handful other ITW innovations were honoured too.<\/p>\n<p>All the innovations were recognized by short videos highlighting the special aspects of the given invention, and from the photos you get an idea of the celebration&rsquo;s atmosphere and you of course see our R&amp;D team receiving the award.<\/p>\n<p>You can read more about the <a href=\"https:\/\/itwgse.com\/pre-conditioned-air\/\" target=\"_blank\" rel=\"noopener\">PCA here<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-24522 size-large\" src=\"https:\/\/itwgse.com\/wp-content\/uploads\/2023\/10\/ITW_Patent_Society_Dinner_2023-29-scaled-1024x683.jpg\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/itwgse.com\/wp-content\/uploads\/2023\/10\/ITW_Patent_Society_Dinner_2023-29-scaled-1024x683.jpg 1024w, https:\/\/itwgse.com\/wp-content\/uploads\/2023\/10\/ITW_Patent_Society_Dinner_2023-29-scaled-300x200.jpg 300w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-24525 size-large\" src=\"https:\/\/itwgse.com\/wp-content\/uploads\/2023\/10\/ITW_Patent_Society_Dinner_2023-31-scaled-1024x683.jpg\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/itwgse.com\/wp-content\/uploads\/2023\/10\/ITW_Patent_Society_Dinner_2023-31-scaled-1024x683.jpg 1024w, https:\/\/itwgse.com\/wp-content\/uploads\/2023\/10\/ITW_Patent_Society_Dinner_2023-31-scaled-300x200.jpg 300w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-24528 size-large\" src=\"https:\/\/itwgse.com\/wp-content\/uploads\/2023\/10\/ITW_Patent_Society_Dinner_2023-10-scaled-1024x683.jpg\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/itwgse.com\/wp-content\/uploads\/2023\/10\/ITW_Patent_Society_Dinner_2023-10-scaled-1024x683.jpg 1024w, https:\/\/itwgse.com\/wp-content\/uploads\/2023\/10\/ITW_Patent_Society_Dinner_2023-10-scaled-300x200.jpg 300w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8230;all with the focus on honoring present and past innovators at ITW.\u00a0 We are pleased to tell that our R&amp;D team members have been&#8230;<\/p>\n","protected":false},"author":11,"featured_media":24519,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-24518","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ikke-kategoriseret"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ITW Patent Society Award Dinner 2023 - ITW GSE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/itwgse.com\/news\/itw-patent-society-award-dinner-2023\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ITW Patent Society Award Dinner 2023 - ITW GSE\" \/>\n<meta property=\"og:description\" content=\"&#8230;all with the focus on honoring present and past innovators at ITW.\u00a0 We are pleased to tell that our R&amp;D team members have been...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/itwgse.com\/news\/itw-patent-society-award-dinner-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"ITW GSE\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ITWGSE\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-31T12:56:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/itwgse.com\/wp-content\/uploads\/2023\/10\/ITW_Patent_Society_Dinner_2023-100-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Anna Dyg Ernst\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Anna Dyg Ernst\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/itwgse.com\/news\/itw-patent-society-award-dinner-2023\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/itwgse.com\/news\/itw-patent-society-award-dinner-2023\/\"},\"author\":{\"name\":\"Anna Dyg Ernst\",\"@id\":\"https:\/\/itwgse.com\/#\/schema\/person\/a5d0ec78a16b13ddeed24c30d1b3abfe\"},\"headline\":\"ITW Patent Society Award Dinner 2023\",\"datePublished\":\"2023-10-31T12:56:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/itwgse.com\/news\/itw-patent-society-award-dinner-2023\/\"},\"wordCount\":116,\"publisher\":{\"@id\":\"https:\/\/itwgse.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/itwgse.com\/news\/itw-patent-society-award-dinner-2023\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/itwgse.com\/wp-content\/uploads\/2023\/10\/ITW_Patent_Society_Dinner_2023-100-scaled.jpg\",\"articleSection\":[\"Ikke-kategoriseret\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/itwgse.com\/news\/itw-patent-society-award-dinner-2023\/\",\"url\":\"https:\/\/itwgse.com\/news\/itw-patent-society-award-dinner-2023\/\",\"name\":\"ITW Patent Society Award Dinner 2023 - ITW GSE\",\"isPartOf\":{\"@id\":\"https:\/\/itwgse.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/itwgse.com\/news\/itw-patent-society-award-dinner-2023\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/itwgse.com\/news\/itw-patent-society-award-dinner-2023\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/itwgse.com\/wp-content\/uploads\/2023\/10\/ITW_Patent_Society_Dinner_2023-100-scaled.jpg\",\"datePublished\":\"2023-10-31T12:56:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/itwgse.com\/news\/itw-patent-society-award-dinner-2023\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/itwgse.com\/news\/itw-patent-society-award-dinner-2023\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/itwgse.com\/news\/itw-patent-society-award-dinner-2023\/#primaryimage\",\"url\":\"https:\/\/itwgse.com\/wp-content\/uploads\/2023\/10\/ITW_Patent_Society_Dinner_2023-100-scaled.jpg\",\"contentUrl\":\"https:\/\/itwgse.com\/wp-content\/uploads\/2023\/10\/ITW_Patent_Society_Dinner_2023-100-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"itw gse pca award\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/itwgse.com\/news\/itw-patent-society-award-dinner-2023\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/itwgse.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ITW Patent Society Award Dinner 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/itwgse.com\/#website\",\"url\":\"https:\/\/itwgse.com\/\",\"name\":\"ITW GSE\",\"description\":\"It&#039;s all about connections\",\"publisher\":{\"@id\":\"https:\/\/itwgse.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/itwgse.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/itwgse.com\/#organization\",\"name\":\"ITW GSE\",\"url\":\"https:\/\/itwgse.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/itwgse.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/itwgse.com\/wp-content\/uploads\/2018\/11\/logo.png\",\"contentUrl\":\"https:\/\/itwgse.com\/wp-content\/uploads\/2018\/11\/logo.png\",\"width\":302,\"height\":237,\"caption\":\"ITW GSE\"},\"image\":{\"@id\":\"https:\/\/itwgse.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/ITWGSE\/\",\"https:\/\/www.linkedin.com\/company\/itw-gse\/\",\"https:\/\/www.youtube.com\/channel\/UCTUIMvyaOPfYIqzP8enZ8yw\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/itwgse.com\/#\/schema\/person\/a5d0ec78a16b13ddeed24c30d1b3abfe\",\"name\":\"Anna Dyg Ernst\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/itwgse.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/83b4d6e10e182dff5cdc3859bbdced5f5b331e42444bd79696582f4d3bbbbe9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/83b4d6e10e182dff5cdc3859bbdced5f5b331e42444bd79696582f4d3bbbbe9b?s=96&d=mm&r=g\",\"caption\":\"Anna Dyg Ernst\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ITW Patent Society Award Dinner 2023 - ITW GSE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/itwgse.com\/news\/itw-patent-society-award-dinner-2023\/","og_locale":"fr_FR","og_type":"article","og_title":"ITW Patent Society Award Dinner 2023 - ITW GSE","og_description":"&#8230;all with the focus on honoring present and past innovators at ITW.\u00a0 We are pleased to tell that our R&amp;D team members have been...","og_url":"https:\/\/itwgse.com\/news\/itw-patent-society-award-dinner-2023\/","og_site_name":"ITW GSE","article_publisher":"https:\/\/www.facebook.com\/ITWGSE\/","article_published_time":"2023-10-31T12:56:52+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/itwgse.com\/wp-content\/uploads\/2023\/10\/ITW_Patent_Society_Dinner_2023-100-scaled.jpg","type":"image\/jpeg"}],"author":"Anna Dyg Ernst","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Anna Dyg Ernst","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/itwgse.com\/news\/itw-patent-society-award-dinner-2023\/#article","isPartOf":{"@id":"https:\/\/itwgse.com\/news\/itw-patent-society-award-dinner-2023\/"},"author":{"name":"Anna Dyg Ernst","@id":"https:\/\/itwgse.com\/#\/schema\/person\/a5d0ec78a16b13ddeed24c30d1b3abfe"},"headline":"ITW Patent Society Award Dinner 2023","datePublished":"2023-10-31T12:56:52+00:00","mainEntityOfPage":{"@id":"https:\/\/itwgse.com\/news\/itw-patent-society-award-dinner-2023\/"},"wordCount":116,"publisher":{"@id":"https:\/\/itwgse.com\/#organization"},"image":{"@id":"https:\/\/itwgse.com\/news\/itw-patent-society-award-dinner-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/itwgse.com\/wp-content\/uploads\/2023\/10\/ITW_Patent_Society_Dinner_2023-100-scaled.jpg","articleSection":["Ikke-kategoriseret"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/itwgse.com\/news\/itw-patent-society-award-dinner-2023\/","url":"https:\/\/itwgse.com\/news\/itw-patent-society-award-dinner-2023\/","name":"ITW Patent Society Award Dinner 2023 - ITW GSE","isPartOf":{"@id":"https:\/\/itwgse.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/itwgse.com\/news\/itw-patent-society-award-dinner-2023\/#primaryimage"},"image":{"@id":"https:\/\/itwgse.com\/news\/itw-patent-society-award-dinner-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/itwgse.com\/wp-content\/uploads\/2023\/10\/ITW_Patent_Society_Dinner_2023-100-scaled.jpg","datePublished":"2023-10-31T12:56:52+00:00","breadcrumb":{"@id":"https:\/\/itwgse.com\/news\/itw-patent-society-award-dinner-2023\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/itwgse.com\/news\/itw-patent-society-award-dinner-2023\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/itwgse.com\/news\/itw-patent-society-award-dinner-2023\/#primaryimage","url":"https:\/\/itwgse.com\/wp-content\/uploads\/2023\/10\/ITW_Patent_Society_Dinner_2023-100-scaled.jpg","contentUrl":"https:\/\/itwgse.com\/wp-content\/uploads\/2023\/10\/ITW_Patent_Society_Dinner_2023-100-scaled.jpg","width":2560,"height":1707,"caption":"itw gse pca award"},{"@type":"BreadcrumbList","@id":"https:\/\/itwgse.com\/news\/itw-patent-society-award-dinner-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/itwgse.com\/fr\/"},{"@type":"ListItem","position":2,"name":"ITW Patent Society Award Dinner 2023"}]},{"@type":"WebSite","@id":"https:\/\/itwgse.com\/#website","url":"https:\/\/itwgse.com\/","name":"ITW GSE","description":"It&#039;s all about connections","publisher":{"@id":"https:\/\/itwgse.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/itwgse.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/itwgse.com\/#organization","name":"ITW GSE","url":"https:\/\/itwgse.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/itwgse.com\/#\/schema\/logo\/image\/","url":"https:\/\/itwgse.com\/wp-content\/uploads\/2018\/11\/logo.png","contentUrl":"https:\/\/itwgse.com\/wp-content\/uploads\/2018\/11\/logo.png","width":302,"height":237,"caption":"ITW GSE"},"image":{"@id":"https:\/\/itwgse.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ITWGSE\/","https:\/\/www.linkedin.com\/company\/itw-gse\/","https:\/\/www.youtube.com\/channel\/UCTUIMvyaOPfYIqzP8enZ8yw"]},{"@type":"Person","@id":"https:\/\/itwgse.com\/#\/schema\/person\/a5d0ec78a16b13ddeed24c30d1b3abfe","name":"Anna Dyg Ernst","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/itwgse.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/83b4d6e10e182dff5cdc3859bbdced5f5b331e42444bd79696582f4d3bbbbe9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/83b4d6e10e182dff5cdc3859bbdced5f5b331e42444bd79696582f4d3bbbbe9b?s=96&d=mm&r=g","caption":"Anna Dyg Ernst"}}]}},"_links":{"self":[{"href":"https:\/\/itwgse.com\/fr\/wp-json\/wp\/v2\/posts\/24518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/itwgse.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/itwgse.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/itwgse.com\/fr\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/itwgse.com\/fr\/wp-json\/wp\/v2\/comments?post=24518"}],"version-history":[{"count":3,"href":"https:\/\/itwgse.com\/fr\/wp-json\/wp\/v2\/posts\/24518\/revisions"}],"predecessor-version":[{"id":24533,"href":"https:\/\/itwgse.com\/fr\/wp-json\/wp\/v2\/posts\/24518\/revisions\/24533"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/itwgse.com\/fr\/wp-json\/wp\/v2\/media\/24519"}],"wp:attachment":[{"href":"https:\/\/itwgse.com\/fr\/wp-json\/wp\/v2\/media?parent=24518"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/itwgse.com\/fr\/wp-json\/wp\/v2\/categories?post=24518"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/itwgse.com\/fr\/wp-json\/wp\/v2\/tags?post=24518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}